{"id":5038,"date":"2020-07-23T16:40:26","date_gmt":"2020-07-23T16:40:26","guid":{"rendered":"https:\/\/destinoysabor.com\/blog\/?p=5038"},"modified":"2020-12-23T08:07:39","modified_gmt":"2020-12-23T08:07:39","slug":"documental-go-spain","status":"publish","type":"post","link":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/","title":{"rendered":"Go Spain! reconstruyendo el pa\u00eds desde el enoturismo y la gastronom\u00eda"},"content":{"rendered":"<p>Todos, algunos m\u00e1s y otros, los afortunados, menos,<strong> hemos sufrido este a\u00f1o 2020 por el Covid<\/strong>. Acabamos de recibir la informaci\u00f3n de un proyecto, <strong>el rodaje del documental Go Spain! que trata de ayudar a la reconstrucci\u00f3n de una de nuestras mayores industrias en Espa\u00f1a<\/strong>. Se trata del turismo, aunque centrada en el enoturismo, la gastronom\u00eda y la cultura, como hechos diferenciadores de nuestro territorio.<\/p>\n<p>A lo largo de este documental, que se est\u00e1 rodando, con los chefs Francis Paniego y Carolina S\u00e1nchez, el experto en vinos Jos\u00e9 Ram\u00f3n Jim\u00e9nez y la en\u00f3loga Mar\u00eda Vargas, a modo de embajadores, se quiere dar a conocer y poner en valor <strong>todos los recursos tur\u00edsticos de esta tierra tan interesante como es La Rioja<\/strong>.<\/p>\n<blockquote><p>Este documental busca dar a conocer iniciativas de esta reconstrucci\u00f3n en lugares como Logro\u00f1o, Arnedo, San Mill\u00e1n de la Cogolla, \u00c1balos o San Vicente de la Sonsierra, donde la creatividad y el talento se ponen al servicio de un bien com\u00fan.<\/p><\/blockquote>\n<div id=\"attachment_5030\" style=\"width: 590px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5030\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/94009151ed3ac27b8ca6a878250de476.jpg\" alt=\"Monasterio de Yuso en San Mill\u00e1n - Imagen del Monasterio\" width=\"580\" height=\"326\" class=\"size-full wp-image-5030\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/94009151ed3ac27b8ca6a878250de476.jpg 580w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/94009151ed3ac27b8ca6a878250de476-300x169.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/94009151ed3ac27b8ca6a878250de476-330x185.jpg 330w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><p id=\"caption-attachment-5030\" class=\"wp-caption-text\">Monasterio de Yuso en San Mill\u00e1n &#8211; Imagen del Monasterio<\/p><\/div>\n<h2>La Rioja como regi\u00f3n referente del enoturismo<\/h2>\n<p>Como nosotros mismos hemos podido descubrir, y a\u00fan nos queda mucho, <strong>este peque\u00f1o territorio posee grandes recursos de tur\u00edsticos que sit\u00faan a esta comunidad, en un referente de destino de interior<\/strong>, donde el enoturismo destaca de forma sorprendente. <\/p>\n<p>Pero a esto, tal y como nos contaron en varias experiencias los amigos de La Mesa del Conde, se le une <a href=\"https:\/\/lamesadelconde.es\/gastroexperiencia-2-0-en-la-rioja-en-la-taberna-la-reyes\/\" rel=\"noopener noreferrer\" target=\"_blank\">la gastronom\u00eda<\/a>, pero tambi\u00e9n la cultura, el patrimonio y los espacios naturales.<\/p>\n<h3>La presentaci\u00f3n del proyecto<\/h3>\n<p>Esta iniciativa <strong>fue presentada en el restaurante Tondeluna<\/strong>, con la participaci\u00f3n de la directora general de Turismo, Amaia L\u00f3pez de Heredia; el creador del proyecto \u2018Go, Spain!\u2019 y CEO de la productora THINK, \u00c1ngel Tapia; adem\u00e1s del chef Francis Paniego y el experto en vinos Jos\u00e9 Ram\u00f3n Jim\u00e9nez.<\/p>\n<div id=\"attachment_5042\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5042\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/de40b999c242b4586251af6ab31d869b.jpg\" alt=\"Presentaci\u00f3n del documental Go Spain - Imagen de Turismo La Rioja\" width=\"640\" height=\"360\" class=\"size-full wp-image-5042\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/de40b999c242b4586251af6ab31d869b.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/de40b999c242b4586251af6ab31d869b-300x169.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/de40b999c242b4586251af6ab31d869b-330x186.jpg 330w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-5042\" class=\"wp-caption-text\">Presentaci\u00f3n del documental Go Spain &#8211; Imagen de Turismo La Rioja<\/p><\/div>\n<h3>Los objetivos<\/h3>\n<p>Durante la presentaci\u00f3n, <strong>Do\u00f1a Amaia L\u00f3pez de Heredia explic\u00f3 que esta propuesta se alinea con la campa\u00f1a tur\u00edstica del gobierno de la regi\u00f3n<\/strong>, apelando a las cosas peque\u00f1as que todos hemos echado de menos, al tiempo que animaba a los riojanos a ser los primeros embajadores de su tierra.<\/p>\n<div id=\"attachment_5045\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5045\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/GoSpain-ante-los-medios-Imagen-de-Turismo-La-Rioja.jpg\" alt=\"Go Spain ante los medios - Imagen de Turismo La Rioja\" width=\"640\" height=\"360\" class=\"size-full wp-image-5045\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/GoSpain-ante-los-medios-Imagen-de-Turismo-La-Rioja.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/GoSpain-ante-los-medios-Imagen-de-Turismo-La-Rioja-300x169.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/GoSpain-ante-los-medios-Imagen-de-Turismo-La-Rioja-330x186.jpg 330w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-5045\" class=\"wp-caption-text\">Go Spain ante los medios &#8211; Imagen de Turismo La Rioja<\/p><\/div>\n<p>De esta forma <strong>se pretende reactivar el turismo en general en Espa\u00f1a y en particular en esta comunidad<\/strong>; y una de las mejores formas de hacerlo es a trav\u00e9s de las personas que hacen esto posible, as\u00ed como a los recursos tan atractivos como la gastronom\u00eda, las bodegas, la cultura y la naturaleza.<\/p>\n<h4>Go Spain!<\/h4>\n<p>Esta propuesta <strong>est\u00e1 desarroll\u00e1ndose por  la productora THINK, creadora de \u2018<em>Spain Passion<\/em>\u2019<\/strong>, una gu\u00eda tur\u00edstica en formato serie que ya rod\u00f3 anteriormente en La Rioja varios cap\u00edtulos. <\/p>\n<h4>Vinos, y mucho m\u00e1s que vinos<\/h4>\n<p>Tal y como destac\u00f3 el chef, Francis Paniego, <strong>en La Rioja hay mucho vino, pero igualmente mucho de gastronom\u00eda, tanto que incluso ha trascendido como &#8220;cocinar a la riojana&#8221;<\/strong>. <\/p>\n<div id=\"attachment_5015\" style=\"width: 590px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5015\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/Comer-en-Rte.-de-la-Posada-Santa-Rita-de-Enciso-Destino-y-Sabor.jpg\" alt=\"Comer en Rte. de la Posada Santa Rita de Enciso - Destino y Sabor\" width=\"580\" height=\"387\" class=\"size-full wp-image-5015\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/Comer-en-Rte.-de-la-Posada-Santa-Rita-de-Enciso-Destino-y-Sabor.jpg 580w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/Comer-en-Rte.-de-la-Posada-Santa-Rita-de-Enciso-Destino-y-Sabor-300x200.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/Comer-en-Rte.-de-la-Posada-Santa-Rita-de-Enciso-Destino-y-Sabor-330x220.jpg 330w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/Comer-en-Rte.-de-la-Posada-Santa-Rita-de-Enciso-Destino-y-Sabor-296x197.jpg 296w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/><p id=\"caption-attachment-5015\" class=\"wp-caption-text\">Comer en Rte. de la Posada Santa Rita de Enciso &#8211; Destino y Sabor<\/p><\/div>\n<blockquote><p>&#8220;Es algo muy nuestro y hay una forma de ser muy a la riojana, de la que no siempre somos conscientes, pero que crea una identidad propia y convierte nuestro destino en un destino muy de verdad y muy aut\u00e9ntico&#8221;<\/p><\/blockquote>\n<p>Esta misma idea la apunto tambi\u00e9n Jos\u00e9 Ram\u00f3n Jim\u00e9nez, <strong>quien adem\u00e1s ha destacado la importancia de \u201cincluir a La Rioja en un proyecto con tal elenco de cultura\u201d<\/strong>. <\/p>\n<h3>Conversaciones y viajes sensoriales<\/h3>\n<p>Un documental, por muy bueno que sea, a\u00fan es incapaz de transmitir las vivencias que quiere mostrar, <strong>no obstante, este documental con todo sus recorridos y conversaciones se estrenar\u00e1n el pr\u00f3ximo noviembre, distribuy\u00e9ndose por Espa\u00f1a, Europa y otros continentes<\/strong>, en lugares tan importantes como Estados Unidos, Brasil, Jap\u00f3n o China, entre otros.<\/p>\n<div id=\"attachment_5043\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5043\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Embajadores-de-GoSpain-en-La-Rioja-Imagen-de-Turismo-La-Rioja.jpg\" alt=\"Embajadores de Go Spain en La Rioja - Imagen de Turismo La Rioja\" width=\"640\" height=\"360\" class=\"size-full wp-image-5043\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Embajadores-de-GoSpain-en-La-Rioja-Imagen-de-Turismo-La-Rioja.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Embajadores-de-GoSpain-en-La-Rioja-Imagen-de-Turismo-La-Rioja-300x169.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Embajadores-de-GoSpain-en-La-Rioja-Imagen-de-Turismo-La-Rioja-330x186.jpg 330w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-5043\" class=\"wp-caption-text\">Embajadores de Go Spain en La Rioja &#8211; Imagen de Turismo La Rioja<\/p><\/div>\n<p><strong>Los beneficios generados por este documental, se destinar\u00e1n al Banco de Alimentos<\/strong> para ayudar a remediar las consecuencias del Covid-19.<\/p>\n<p><center><iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/kPGYSeqAJJ4\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/center><\/p>\n<h3>\u00bfY por qu\u00e9 viajar a La Rioja?<\/h3>\n<p>Posiblemente La Rioja sea m\u00e1s conocida por sus vinos, los compa\u00f1eros de La mesa del Conde lo saben bien con sus <a href=\"https:\/\/lamesadelconde.es\/?s=DOCa.+Rioja\" rel=\"noopener noreferrer\" target=\"_blank\">m\u00faltiples catas y referencias de sus vinos<\/a>, unos vinos en general bien estructurados y con buenas crianzas. Pero igualmente <strong>el enoturismo, o turismo del vino, es una forma m\u00e1s de vivir y experimentar la cultura del vino, m\u00e1s all\u00e1 del vino<\/strong>.<\/p>\n<p>En La Rioja lo saben bien, <strong>contando en su territorio con muchas de las llamadas &#8220;Catedrales del Vino&#8221;<\/strong>, nosotros mismos <strong>vivimos la experiencia en Haro de su barrio de la Estaci\u00f3n<\/strong>, con bodegas tan interesantes y emblem\u00e1ticas como <a href=\"https:\/\/destinoysabor.com\/blog\/bodegas-muga\/\">Muga<\/a>,.. pero hay muchas m\u00e1s, a cual m\u00e1s impresionante e interesante desde el punto de vista del turismo. <\/p>\n<div id=\"attachment_4657\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-4657\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/12\/1130f9202b0a1636065750484e9cdf00.jpg\" alt=\"Barrio de la Estaci\u00f3n de Haro - Destino y Sabor\" width=\"640\" height=\"400\" class=\"size-full wp-image-4657\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/12\/1130f9202b0a1636065750484e9cdf00.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/12\/1130f9202b0a1636065750484e9cdf00-300x188.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/12\/1130f9202b0a1636065750484e9cdf00-330x206.jpg 330w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-4657\" class=\"wp-caption-text\">Barrio de la Estaci\u00f3n de Haro &#8211; Destino y Sabor<\/p><\/div>\n<p>Pero patrimonialmente hablando, hay <strong>muchos pueblos interesantes, ricos en su patrimonio hist\u00f3rico art\u00edstico<\/strong>. Sin irnos m\u00e1s lejos Haro y su iglesia mayor. Otros, igual menos conocidos, pero igualmente interesantes es <a href=\"https:\/\/destinoysabor.com\/blog\/navarrete-mas-que-un-alto-en-el-camino\/\">Navarrete<\/a>, donde adem\u00e1s te empapas del Camino Jacobeo, que el pr\u00f3ximo a\u00f1o 2021 ser\u00e1 a\u00f1o Jacobeo. Una excusa perfecta para &#8220;<a href=\"https:\/\/destinoysabor.com\/blog\/una-parada-en-el-camino\/\">hacer una parada en el Camino<\/a>&#8220;, es disfrutar de Bodegas Corral.<\/p>\n<div id=\"attachment_4561\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-4561\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Vistas-desde-el-cerro-de-Navarrete-donde-hubo-una-fortaleza-Destino-y-Sabor.jpg\" alt=\"Vistas desde el cerro de Navarrete, donde hubo una fortaleza - Destino y Sabor\" width=\"640\" height=\"427\" class=\"size-full wp-image-4561\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Vistas-desde-el-cerro-de-Navarrete-donde-hubo-una-fortaleza-Destino-y-Sabor.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Vistas-desde-el-cerro-de-Navarrete-donde-hubo-una-fortaleza-Destino-y-Sabor-300x200.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Vistas-desde-el-cerro-de-Navarrete-donde-hubo-una-fortaleza-Destino-y-Sabor-330x220.jpg 330w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Vistas-desde-el-cerro-de-Navarrete-donde-hubo-una-fortaleza-Destino-y-Sabor-296x197.jpg 296w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-4561\" class=\"wp-caption-text\">Vistas desde el cerro de Navarrete, donde hubo una fortaleza &#8211; Destino y Sabor<\/p><\/div>\n<p>Otros lugares relacionados con la cultura son <strong>los Monasterios de Suso y Yuso, entre ellos se form\u00f3 nuestra lengua tan universal,<\/strong> como lo es el Castellano. O Santo Domingo de la Calzada,..<\/p>\n<p>Pero si nos queremos detener en gastronom\u00eda, <strong>Calahorra y toda su huerta<\/strong>, fuente de de mil y una elaboraciones esperan en La Rioja Oriental al visitante.<\/p>\n<div id=\"attachment_4632\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-4632\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Iglesia-de-Calahorra-Imagen-Turismo-La-Rioja.jpg\" alt=\"Iglesia de Calahorra - Imagen Turismo La Rioja\" width=\"640\" height=\"427\" class=\"size-full wp-image-4632\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Iglesia-de-Calahorra-Imagen-Turismo-La-Rioja.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Iglesia-de-Calahorra-Imagen-Turismo-La-Rioja-300x200.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Iglesia-de-Calahorra-Imagen-Turismo-La-Rioja-330x220.jpg 330w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2019\/11\/Iglesia-de-Calahorra-Imagen-Turismo-La-Rioja-296x197.jpg 296w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-4632\" class=\"wp-caption-text\">Iglesia de Calahorra &#8211; Imagen Turismo La Rioja<\/p><\/div>\n<p>Y si de historia y naturaleza, en toda la Rioja baja se encuentran <strong>algunos de los m\u00e1s importantes yacimientos de <a href=\"https:\/\/destinocastillayleon.es\/index\/ruta-los-dinosaurios-soria\/\" rel=\"noopener noreferrer\" target=\"_blank\">icnitas<\/a><\/strong>, huellas de dinosaurios que recorrieron esta tierra hace millones de a\u00f1o. Hoy tres importantes <a href=\"https:\/\/destinoysabor.com\/blog\/tras-los-dinosaurios-en-la-rioja\/\">rutas enlazan diferentes yacimientos<\/a>. A lo que se unen varios museos paleontol\u00f3gicos y uno de los reclamos de turismo familiar m\u00e1s aconsejable, <a href=\"https:\/\/destinoysabor.com\/blog\/enciso-y-su-barranco-perdido\/\">el Parque tem\u00e1tico y de aventuras &#8220;El Barranco Perdido&#8221;<\/a>. En fin, sobran los motivos y falta el tiempo para recorrerlo todo.<\/p>\n<div id=\"attachment_5005\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-5005\" src=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/e5847d42979af84578bc27f10f1e9fa9.jpg\" alt=\"Modelo de dinosaurios enfrent\u00e1ndose en Enciso - Destino y Sabor\" width=\"640\" height=\"427\" class=\"size-full wp-image-5005\" srcset=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/e5847d42979af84578bc27f10f1e9fa9.jpg 640w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/e5847d42979af84578bc27f10f1e9fa9-300x200.jpg 300w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/e5847d42979af84578bc27f10f1e9fa9-330x220.jpg 330w, https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/06\/e5847d42979af84578bc27f10f1e9fa9-296x197.jpg 296w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-5005\" class=\"wp-caption-text\">Modelo de dinosaurios enfrent\u00e1ndose en Enciso &#8211; Destino y Sabor<\/p><\/div>\n<p>Y ya veis, que lo que sobran son motivos. Toda Espa\u00f1a, incluida la Espa\u00f1a del interior, es un buen destino para hacer una escapada, unas vacaciones o simplemente, una parada. <strong>&#8220;Va sobrada&#8221; de recursos y productos tur\u00edsticos<\/strong>. Y si no te hemos convencido a\u00fan, seguro que el documental Go Spain! lo hace.<\/p>\n<h4>Tambi\u00e9n te puede interesar<\/h4>\n<ul>\n<li><a href=\"https:\/\/destinoysabor.com\/blog\/escapar-en-el-puente-de-la-constitucion\/#La-Rioja\">Esc\u00e1pate por La Rioja!<\/a>.<\/li>\n<li><a href=\"https:\/\/destinoysabor.com\/blog\/tras-los-dinosaurios-en-la-rioja\/\">Tras los dinosaurios en La Rioja<\/a>.<\/li>\n<li><a href=\"https:\/\/destinoysabor.com\/blog\/navarrete-mas-que-un-alto-en-el-camino\/\">Diversi\u00f3n entre dinosaurios en Enciso y su Barranco Perdido<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Descubrimos el documental GoSpain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.<\/p>\n","protected":false},"author":2,"featured_media":5047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_3437733573_3437733573":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":""},"categories":[1,24,203],"tags":[652,653,555],"class_list":["post-5038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-del-turismo-gastronomico","category-la-rioja","category-no-rrss","tag-actualidad","tag-go-spain","tag-la-rioja"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja<\/title>\n<meta name=\"description\" content=\"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja - Destino y Sabor\" \/>\n<meta property=\"og:description\" content=\"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/\" \/>\n<meta property=\"og:site_name\" content=\"Destino y Sabor\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/destinoysabor\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-23T16:40:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-23T08:07:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David V\u00e1zquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja - Destino y Sabor\" \/>\n<meta name=\"twitter:description\" content=\"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@Destino_Sabor\" \/>\n<meta name=\"twitter:site\" content=\"@Destino_Sabor\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David V\u00e1zquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/\",\"url\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/\",\"name\":\"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja\",\"isPartOf\":{\"@id\":\"https:\/\/destinoysabor.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg\",\"datePublished\":\"2020-07-23T16:40:26+00:00\",\"dateModified\":\"2020-12-23T08:07:39+00:00\",\"author\":{\"@id\":\"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/87dc8dd6f102c79f8099580c399f2920\"},\"description\":\"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.\",\"breadcrumb\":{\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage\",\"url\":\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg\",\"contentUrl\":\"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg\",\"width\":1000,\"height\":460,\"caption\":\"Documental Go Spain\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/destinoysabor.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Go Spain! reconstruyendo el pa\u00eds desde el enoturismo y la gastronom\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/#website\",\"url\":\"https:\/\/destinoysabor.com\/blog\/\",\"name\":\"Destino y Sabor\",\"description\":\"los mejores planes para foodies y winelovers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/destinoysabor.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/87dc8dd6f102c79f8099580c399f2920\",\"name\":\"David V\u00e1zquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cd12db6c575a90c3b75cfa0f794b74d425201c768612fad17e9f13cd33d48be8?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cd12db6c575a90c3b75cfa0f794b74d425201c768612fad17e9f13cd33d48be8?s=96&r=g\",\"caption\":\"David V\u00e1zquez\"},\"sameAs\":[\"https:\/\/lamesadelconde.es\"],\"url\":\"https:\/\/destinoysabor.com\/blog\/author\/david-vazquez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja","description":"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/","og_locale":"es_ES","og_type":"article","og_title":"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja - Destino y Sabor","og_description":"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.","og_url":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/","og_site_name":"Destino y Sabor","article_publisher":"https:\/\/www.facebook.com\/destinoysabor\/","article_published_time":"2020-07-23T16:40:26+00:00","article_modified_time":"2020-12-23T08:07:39+00:00","og_image":[{"width":1000,"height":460,"url":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","type":"image\/jpeg"}],"author":"David V\u00e1zquez","twitter_card":"summary_large_image","twitter_title":"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja - Destino y Sabor","twitter_description":"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.","twitter_image":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","twitter_creator":"@Destino_Sabor","twitter_site":"@Destino_Sabor","twitter_misc":{"Escrito por":"David V\u00e1zquez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/","url":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/","name":"Go Spain! un documental para el turismo y la gastronom\u00eda de La Rioja","isPartOf":{"@id":"https:\/\/destinoysabor.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage"},"image":{"@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage"},"thumbnailUrl":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","datePublished":"2020-07-23T16:40:26+00:00","dateModified":"2020-12-23T08:07:39+00:00","author":{"@id":"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/87dc8dd6f102c79f8099580c399f2920"},"description":"Descubrimos el documental Go Spain! el talento audiovisual junto a los embajadores de La Rioja para dinamizar el turismo de este hermoso territorio.","breadcrumb":{"@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/destinoysabor.com\/blog\/documental-go-spain\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#primaryimage","url":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","contentUrl":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","width":1000,"height":460,"caption":"Documental Go Spain"},{"@type":"BreadcrumbList","@id":"https:\/\/destinoysabor.com\/blog\/documental-go-spain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/destinoysabor.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Go Spain! reconstruyendo el pa\u00eds desde el enoturismo y la gastronom\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/destinoysabor.com\/blog\/#website","url":"https:\/\/destinoysabor.com\/blog\/","name":"Destino y Sabor","description":"los mejores planes para foodies y winelovers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/destinoysabor.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/87dc8dd6f102c79f8099580c399f2920","name":"David V\u00e1zquez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/destinoysabor.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cd12db6c575a90c3b75cfa0f794b74d425201c768612fad17e9f13cd33d48be8?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd12db6c575a90c3b75cfa0f794b74d425201c768612fad17e9f13cd33d48be8?s=96&r=g","caption":"David V\u00e1zquez"},"sameAs":["https:\/\/lamesadelconde.es"],"url":"https:\/\/destinoysabor.com\/blog\/author\/david-vazquez\/"}]}},"jetpack_featured_media_url":"https:\/\/destinoysabor.com\/blog\/wp-content\/uploads\/2020\/07\/Documental-Go-Spain.jpg","_links":{"self":[{"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/posts\/5038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/comments?post=5038"}],"version-history":[{"count":8,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/posts\/5038\/revisions"}],"predecessor-version":[{"id":5050,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/posts\/5038\/revisions\/5050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/media\/5047"}],"wp:attachment":[{"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/media?parent=5038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/categories?post=5038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/destinoysabor.com\/blog\/wp-json\/wp\/v2\/tags?post=5038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}